{"id":805,"date":"2020-02-11T23:05:08","date_gmt":"2020-02-11T23:05:08","guid":{"rendered":"http:\/\/www.elparlante.es\/granpantalla\/?p=805"},"modified":"2020-06-15T20:10:31","modified_gmt":"2020-06-15T20:10:31","slug":"3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020","status":"publish","type":"post","link":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/","title":{"rendered":"3 razones para hacer un festival de cine sobre personas mayores en 2020"},"content":{"rendered":"\n<p class=\"has-drop-cap has-medium-font-size wp-block-paragraph\">Siempre nos preguntan de d\u00f3nde surge la idea de hacer un festival de cine y por qu\u00e9 sobre personas mayores. Somos <a href=\"http:\/\/elparlante.es\">una asociaci\u00f3n cultural<\/a> y nos mueve lo social, as\u00ed que por qu\u00e9 no sumar nuestras motivaciones para crear algo novedoso y diferente.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20190606\/que-hacer-hoy-barcelona-jueves-6-junio-2019-7489213\">La GRAN Pantalla!<\/a> es un espacio para disfrutar del cine desde una nueva perspectiva, poniendo el foco en la manera como est\u00e1n representadas las personas mayores. Pero, el festival tambi\u00e9n fue pensado como un lugar de aprendizaje y debate, para hablar de la industria y de los temas que se vuelven tab\u00fa, tambi\u00e9n en el cine, cuando envejecemos.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">En la <a href=\"http:\/\/lagranpantallafestival.elparlante.es\/programacion\/\">primera edici\u00f3n<\/a> de La GRAN Pantalla! nos dedicamos a buscar y proyectar nuevas miradas sobre el envejecimiento. As\u00ed que, con una muestra de ocho pel\u00edculas, diecis\u00e9is cortometrajes en competici\u00f3n y dos sesiones de cine f\u00f3rum, abrimos las puertas de los Cines Girona a m\u00e1s de dos mil espectadores durante tres d\u00edas de Festival.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">En 2019 nos lanzamos al debate feminista sobre las problem\u00e1ticas con las que se encuentran las actrices y las posibilidades que tienen, o dejan de tener, con el paso del tiempo. Y tambi\u00e9n proyectamos pel\u00edculas sobre personas mayores LGTBIQ y abrimos una mesa para hablar sobre su representaci\u00f3n en el cine.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/MG_4997-33-1024x683-1.jpg\" alt=\"\" data-id=\"1581\" data-full-url=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/MG_4997-33-1024x683-1.jpg\" data-link=\"https:\/\/lagranpantallafestival.com\/es\/2020\/02\/11\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/mg_4997-33-1024x683-1\/\" class=\"wp-image-1581\" srcset=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/MG_4997-33-1024x683-1.jpg 1024w, https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/MG_4997-33-1024x683-1-980x654.jpg 980w, https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/MG_4997-33-1024x683-1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF2096-23-1024x683-1.jpg\" alt=\"\" data-id=\"1580\" data-full-url=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF2096-23-1024x683-1.jpg\" data-link=\"https:\/\/lagranpantallafestival.com\/es\/2020\/02\/11\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/dscf2096-23-1024x683-1\/\" class=\"wp-image-1580\" srcset=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF2096-23-1024x683-1.jpg 1024w, https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF2096-23-1024x683-1-980x654.jpg 980w, https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF2096-23-1024x683-1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF1941-10-1024x683-1.jpg\" alt=\"\" data-id=\"1579\" data-full-url=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF1941-10-1024x683-1.jpg\" data-link=\"https:\/\/lagranpantallafestival.com\/es\/2020\/02\/11\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/dscf1941-10-1024x683-1\/\" class=\"wp-image-1579\" srcset=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF1941-10-1024x683-1.jpg 1024w, https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF1941-10-1024x683-1-980x654.jpg 980w, https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/DSCF1941-10-1024x683-1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">La segunda edici\u00f3n<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">La segunda edici\u00f3n del Festival Internacional de Cine de las Personas Mayores La GRAN Pantalla! ya se est\u00e1 gestando y se llevar\u00e1 a cabo del 18 al 21 de junio de 2020. Estamos trabajando para consolidar un espacio importante y necesario como este, dentro de la agenda cultural de la ciudad. Pero, \u00bfcu\u00e1les son las razones para hacerlo?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Es una cuesti\u00f3n de representaci\u00f3n<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El p\u00fablico mayoritario de las salas de cine no comerciales de la ciudad tiene m\u00e1s de sesenta a\u00f1os, y esta franja de edad es curiosamente la menos visibilizada. Esta falta de representaci\u00f3n en el vasto universo cinematogr\u00e1fico es un tema recurrente durante las formaciones y procesos de sensibilizaci\u00f3n que hace <a href=\"https:\/\/elparlante.es\/\">elParlante<\/a> con las personas mayores, en diferentes centros c\u00edvicos y casales de Barcelona.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. La promoci\u00f3n de contenidos audiovisuales diversos<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Este festival es una gran oportunidad para presentar nuevos talentos del mundo cinematogr\u00e1fico, y a otras y otros m\u00e1s consolidados, que siguen trabajando incansablemente, a\u00fan despu\u00e9s de la \u00abedad de jubilaci\u00f3n\u00bb. Es el espacio id\u00f3neo para promover una nueva mirada sobre las personas mayores, que incluya la diversidad de origen, g\u00e9nero y\/o sexualidad, pero tambi\u00e9n la diversidad funcional y ps\u00edquica. Que muestre las muchas formas de ser mayor y ponga en escena las problem\u00e1ticas que surgen en esta etapa de la vida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. El debate que promueve el s\u00e9ptimo arte<\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Los espacios de cine f\u00f3rum que hemos creado dentro de la programaci\u00f3n de La GRAN Pantalla! tienen como objetivo convocar a los y las profesionales del sector y amantes del cine, para debatir sobre las pel\u00edculas proyectadas. Es en este espacio donde se muestra el car\u00e1cter social de nuestro proyecto, y donde ofrecemos a las personas mayores que asisten un espacio para decir lo que piensan y lo que sienten al ver los contenidos propuestos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/mapa-festhome-convocatoria-e1581415433746-1024x589.png\" alt=\"\" class=\"wp-image-1578\"\/><figcaption>Mapa de los paises de donde nos han enviado cortometrajes para la competici\u00f3n. Festhome.<\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Novedades de la Convocatoria 2020<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">El II Festival Internacional de Cine de las Personas Mayores La GRAN Pantalla! ya abri\u00f3 su convocatoria de cortometrajes para competici\u00f3n en <a href=\"https:\/\/festhome.com\/f\/4632\">Festhome<\/a>. Hemos recibido obras de Espa\u00f1a, Chile, Argentina, Brasil, Canad\u00e1, M\u00e9xico, Ecuador, Francia, Egipto, Siria,&nbsp;&nbsp;Ir\u00e1n, Grecia, Albania, Dinamarca, Ruman\u00eda, Ucrania, Polonia, Cuba y Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">A trav\u00e9s de nuestro <a href=\"https:\/\/lagranpantallafestival.com\/es\/noticias\/\">blog<\/a>, podr\u00e1s conocer todas las noticias y novedades de este a\u00f1o, para que puedas programarte desde ya y acompa\u00f1arnos, una vez m\u00e1s en esta fiesta del cine y las personas mayores.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Si quieres unirte al Festival, como socio, socia, voluntario o voluntaria, \u00a1<a href=\"https:\/\/lagranpantallafestival.com\/es\/contacto\/\">cont\u00e1ctanos<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siempre nos preguntan de d\u00f3nde surge la idea de hacer un festival de cine y por qu\u00e9 sobre personas mayores.<\/p>\n","protected":false},"author":5,"featured_media":806,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:paragraph {\"dropCap\":true,\"fontSize\":\"medium\"} -->\n<p class=\"has-drop-cap has-medium-font-size\">Siempre nos preguntan de d\u00f3nde surge la idea de hacer un festival de cine y por qu\u00e9 sobre personas mayores. Somos <a href=\"http:\/\/elparlante.es\">una asociaci\u00f3n cultural<\/a> y nos mueve lo social, as\u00ed que por qu\u00e9 no sumar nuestras motivaciones para crear algo novedoso y diferente.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.elperiodico.com\/es\/ocio-y-cultura\/20190606\/que-hacer-hoy-barcelona-jueves-6-junio-2019-7489213\">La GRAN Pantalla!<\/a> es un espacio para disfrutar del cine desde una nueva perspectiva, poniendo el foco en la manera como est\u00e1n representadas las personas mayores. Pero, el festival tambi\u00e9n fue pensado como un lugar de aprendizaje y debate, para hablar de la industria y de los temas que se vuelven tab\u00fa, tambi\u00e9n en el cine, cuando envejecemos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">En la <a href=\"http:\/\/lagranpantallafestival.elparlante.es\/programacion\/\">primera edici\u00f3n<\/a> de La GRAN Pantalla! nos dedicamos a buscar y proyectar nuevas miradas sobre el envejecimiento. As\u00ed que, con una muestra de ocho pel\u00edculas, diecis\u00e9is cortometrajes en competici\u00f3n y dos sesiones de cine f\u00f3rum, abrimos las puertas de los Cines Girona a m\u00e1s de dos mil espectadores durante tres d\u00edas de Festival.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">En 2019 nos lanzamos al debate feminista sobre las problem\u00e1ticas con las que se encuentran las actrices y las posibilidades que tienen, o dejan de tener, con el paso del tiempo. Y tambi\u00e9n proyectamos pel\u00edculas sobre personas mayores LGTBIQ y abrimos una mesa para hablar sobre su representaci\u00f3n en el cine.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:block {\"ref\":1175} \/-->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:heading -->\n<h2>La segunda edici\u00f3n<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">La segunda edici\u00f3n del Festival Internacional de Cine de las Personas Mayores La GRAN Pantalla! ya se est\u00e1 gestando y se llevar\u00e1 a cabo del 18 al 21 de junio de 2020. Estamos trabajando para consolidar un espacio importante y necesario como este, dentro de la agenda cultural de la ciudad. Pero, \u00bfcu\u00e1les son las razones para hacerlo?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3>1. Es una cuesti\u00f3n de representaci\u00f3n<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">El p\u00fablico mayoritario de las salas de cine no comerciales de la ciudad tiene m\u00e1s de sesenta a\u00f1os, y esta franja de edad es curiosamente la menos visibilizada. Esta falta de representaci\u00f3n en el vasto universo cinematogr\u00e1fico es un tema recurrente durante las formaciones y procesos de sensibilizaci\u00f3n que hace <a href=\"http:\/\/elparlante.es\/\">elParlante<\/a> con las personas mayores, en diferentes centros c\u00edvicos y casales de Barcelona.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3>2. La promoci\u00f3n de contenidos audiovisuales diversos<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Este festival es una gran oportunidad para presentar nuevos talentos del mundo cinematogr\u00e1fico, y a otras y otros m\u00e1s consolidados, que siguen trabajando incansablemente, a\u00fan despu\u00e9s de la \u00abedad de jubilaci\u00f3n\u00bb. Es el espacio id\u00f3neo para promover una nueva mirada sobre las personas mayores, que incluya la diversidad de origen, g\u00e9nero y\/o sexualidad, pero tambi\u00e9n la diversidad funcional y ps\u00edquica. Que muestre las muchas formas de ser mayor y ponga en escena las problem\u00e1ticas que surgen en esta etapa de la vida.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3>3. El debate que promueve el s\u00e9ptimo arte<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Los espacios de cine f\u00f3rum que hemos creado dentro de la programaci\u00f3n de La GRAN Pantalla! tienen como objetivo convocar a los y las profesionales del sector y amantes del cine, para debatir sobre las pel\u00edculas proyectadas. Es en este espacio donde se muestra el car\u00e1cter social de nuestro proyecto, y donde ofrecemos a las personas mayores que asisten un espacio para decir lo que piensan y lo que sienten al ver los contenidos propuestos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Novedades de la Convocatoria 2020<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:block {\"ref\":1176} \/-->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">El II Festival Internacional de Cine de las Personas Mayores La GRAN Pantalla! ya abri\u00f3 su convocatoria de cortometrajes para competici\u00f3n en <a href=\"https:\/\/festhome.com\/f\/4632\">Festhome<\/a>. Hemos recibido obras de Espa\u00f1a, Chile, Argentina, Brasil, Canad\u00e1, M\u00e9xico, Ecuador, Francia, Egipto, Siria,&nbsp;&nbsp;Ir\u00e1n, Grecia, Albania, Dinamarca, Ruman\u00eda, Ucrania, Polonia, Cuba y Rep\u00fablica Dominicana.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">A trav\u00e9s de nuestro <a href=\"https:\/\/lagranpantallafestival.com\/es\/noticias\/\">blog<\/a>, podr\u00e1s conocer todas las noticias y novedades de este a\u00f1o, para que puedas programarte desde ya y acompa\u00f1arnos, una vez m\u00e1s en esta fiesta del cine y las personas mayores.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Si quieres unirte al Festival, como socio, socia, voluntario o voluntaria, \u00a1<a href=\"https:\/\/lagranpantallafestival.com\/es\/contacto\/\">cont\u00e1ctanos<\/a>!<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"1080","footnotes":""},"categories":[71],"tags":[78,80,79,75,81,82,77],"class_list":["post-805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-barcelona","tag-feminismo","tag-festhome","tag-festival-de-cine","tag-la-gran-pantalla-festival","tag-lgtbiq","tag-personas-mayores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 razones para hacer un festival de cine sobre personas mayores en 2020 &#183;<\/title>\n<meta name=\"description\" content=\"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 razones para hacer un festival de cine sobre personas mayores en 2020 &#183;\" \/>\n<meta property=\"og:description\" content=\"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Festival Internacional de Cinema de les Persones Grans de Barcelona: La Gran Pantalla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lagranpantallabcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-11T23:05:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-15T20:10:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/festival-1024x576-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"lagranpantalla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@granpantallabcn\" \/>\n<meta name=\"twitter:site\" content=\"@granpantallabcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lagranpantalla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/\"},\"author\":{\"name\":\"lagranpantalla\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#\\\/schema\\\/person\\\/a742f1a025397e56ee53c6b62b1b3a10\"},\"headline\":\"3 razones para hacer un festival de cine sobre personas mayores en 2020\",\"datePublished\":\"2020-02-11T23:05:08+00:00\",\"dateModified\":\"2020-06-15T20:10:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/\"},\"wordCount\":686,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranpantallafestival.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/festival-1024x576-1.png\",\"keywords\":[\"barcelona\",\"feminismo\",\"festhome\",\"Festival de Cine\",\"la gran pantalla festival\",\"lgtbiq\",\"personas mayores\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/\",\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/\",\"name\":\"3 razones para hacer un festival de cine sobre personas mayores en 2020 &#183;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lagranpantallafestival.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/festival-1024x576-1.png\",\"datePublished\":\"2020-02-11T23:05:08+00:00\",\"dateModified\":\"2020-06-15T20:10:31+00:00\",\"description\":\"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/festival-1024x576-1.png\",\"contentUrl\":\"https:\\\/\\\/lagranpantallafestival.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/festival-1024x576-1.png\",\"width\":1024,\"height\":576,\"caption\":\"Festival Internacional de Cinema de les Persones Grans de Barcelona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 razones para hacer un festival de cine sobre personas mayores en 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/\",\"name\":\"Festival Internacional de Cinema de les Persones Grans de Barcelona: La Gran Pantalla\",\"description\":\"El Festival Internacional de Cine de las personas mayores La gran pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#organization\",\"name\":\"[wpseo_titles]company_nombre\",\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/lagranpantallafestival.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo_web_LaGranPantalla.png?fit=901%2C301&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/lagranpantallafestival.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo_web_LaGranPantalla.png?fit=901%2C301&ssl=1\",\"width\":901,\"height\":301,\"caption\":\"[wpseo_titles]company_nombre\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lagranpantallabcn\\\/\",\"https:\\\/\\\/x.com\\\/granpantallabcn\",\"https:\\\/\\\/www.instagram.com\\\/lagranpantallabcn\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/colectivoelparlante\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#\\\/schema\\\/person\\\/a742f1a025397e56ee53c6b62b1b3a10\",\"name\":\"lagranpantalla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d7d152cbe8c0a34203c3c862e5e0dcb4c426e2e6d438567fb8fb45bec080245?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d7d152cbe8c0a34203c3c862e5e0dcb4c426e2e6d438567fb8fb45bec080245?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d7d152cbe8c0a34203c3c862e5e0dcb4c426e2e6d438567fb8fb45bec080245?s=96&d=mm&r=g\",\"caption\":\"lagranpantalla\"},\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/author\\\/lagranpantalla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 razones para hacer un festival de cine sobre personas mayores en 2020 &#183;","description":"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/","og_locale":"es_ES","og_type":"article","og_title":"3 razones para hacer un festival de cine sobre personas mayores en 2020 &#183;","og_description":"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.","og_url":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/","og_site_name":"Festival Internacional de Cinema de les Persones Grans de Barcelona: La Gran Pantalla","article_publisher":"https:\/\/www.facebook.com\/lagranpantallabcn\/","article_published_time":"2020-02-11T23:05:08+00:00","article_modified_time":"2020-06-15T20:10:31+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/festival-1024x576-1.png","type":"image\/png"}],"author":"lagranpantalla","twitter_card":"summary_large_image","twitter_creator":"@granpantallabcn","twitter_site":"@granpantallabcn","twitter_misc":{"Escrito por":"lagranpantalla","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/#article","isPartOf":{"@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/"},"author":{"name":"lagranpantalla","@id":"https:\/\/lagranpantallafestival.com\/es\/#\/schema\/person\/a742f1a025397e56ee53c6b62b1b3a10"},"headline":"3 razones para hacer un festival de cine sobre personas mayores en 2020","datePublished":"2020-02-11T23:05:08+00:00","dateModified":"2020-06-15T20:10:31+00:00","mainEntityOfPage":{"@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/"},"wordCount":686,"commentCount":0,"publisher":{"@id":"https:\/\/lagranpantallafestival.com\/es\/#organization"},"image":{"@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/festival-1024x576-1.png","keywords":["barcelona","feminismo","festhome","Festival de Cine","la gran pantalla festival","lgtbiq","personas mayores"],"articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/","url":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/","name":"3 razones para hacer un festival de cine sobre personas mayores en 2020 &#183;","isPartOf":{"@id":"https:\/\/lagranpantallafestival.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/#primaryimage"},"image":{"@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/festival-1024x576-1.png","datePublished":"2020-02-11T23:05:08+00:00","dateModified":"2020-06-15T20:10:31+00:00","description":"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.","breadcrumb":{"@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/#primaryimage","url":"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/festival-1024x576-1.png","contentUrl":"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/06\/festival-1024x576-1.png","width":1024,"height":576,"caption":"Festival Internacional de Cinema de les Persones Grans de Barcelona"},{"@type":"BreadcrumbList","@id":"https:\/\/lagranpantallafestival.com\/es\/3-razones-para-hacer-un-festival-de-cine-sobre-personas-mayores-en-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranpantallafestival.com\/es\/"},{"@type":"ListItem","position":2,"name":"3 razones para hacer un festival de cine sobre personas mayores en 2020"}]},{"@type":"WebSite","@id":"https:\/\/lagranpantallafestival.com\/es\/#website","url":"https:\/\/lagranpantallafestival.com\/es\/","name":"Festival Internacional de Cinema de les Persones Grans de Barcelona: La Gran Pantalla","description":"El Festival Internacional de Cine de las personas mayores La gran pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.","publisher":{"@id":"https:\/\/lagranpantallafestival.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranpantallafestival.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lagranpantallafestival.com\/es\/#organization","name":"[wpseo_titles]company_nombre","url":"https:\/\/lagranpantallafestival.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranpantallafestival.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/05\/Logo_web_LaGranPantalla.png?fit=901%2C301&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/05\/Logo_web_LaGranPantalla.png?fit=901%2C301&ssl=1","width":901,"height":301,"caption":"[wpseo_titles]company_nombre"},"image":{"@id":"https:\/\/lagranpantallafestival.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lagranpantallabcn\/","https:\/\/x.com\/granpantallabcn","https:\/\/www.instagram.com\/lagranpantallabcn\/","https:\/\/www.youtube.com\/user\/colectivoelparlante"]},{"@type":"Person","@id":"https:\/\/lagranpantallafestival.com\/es\/#\/schema\/person\/a742f1a025397e56ee53c6b62b1b3a10","name":"lagranpantalla","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d7d152cbe8c0a34203c3c862e5e0dcb4c426e2e6d438567fb8fb45bec080245?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d7d152cbe8c0a34203c3c862e5e0dcb4c426e2e6d438567fb8fb45bec080245?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d7d152cbe8c0a34203c3c862e5e0dcb4c426e2e6d438567fb8fb45bec080245?s=96&d=mm&r=g","caption":"lagranpantalla"},"url":"https:\/\/lagranpantallafestival.com\/es\/author\/lagranpantalla\/"}]}},"_links":{"self":[{"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/posts\/805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/comments?post=805"}],"version-history":[{"count":8,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/posts\/805\/revisions"}],"predecessor-version":[{"id":1583,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/posts\/805\/revisions\/1583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/media\/806"}],"wp:attachment":[{"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/media?parent=805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/categories?post=805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/tags?post=805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}