{"id":2722,"date":"2020-07-20T13:58:46","date_gmt":"2020-07-20T13:58:46","guid":{"rendered":"https:\/\/lagranpantallafestival.com\/?p=2722"},"modified":"2020-07-20T14:28:12","modified_gmt":"2020-07-20T14:28:12","slug":"gracias-gracias-y-gracias","status":"publish","type":"post","link":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/","title":{"rendered":"\u00a1GRACIAS, GRACIAS Y GRACIAS!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gracias a todas las personas que hab\u00e9is colaborado, participado y apoyado esta segunda edici\u00f3n de La GRAN pantalla. Gracias porque sin vuestra confianza, no hubiera sido posible. En esta ocasi\u00f3n, el Festival Internacional de Cine de las Personas Mayores de Barcelona que, a causa de la crisis global relacionada con la Covid-19, apost\u00f3 por una edici\u00f3n virtual y extraordinaria, ha visto multiplicado casi por cinco el n\u00famero de espectadores, respecto a la edici\u00f3n anterior. Alrededor de 10.000 personas han podido disfrutar de esta propuesta que, un a\u00f1o m\u00e1s, se ha convertido en un espacio de encuentro cinematogr\u00e1fico intergeneracional que desmonta los prejuicios y estereotipos sobre las personas mayores.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"EQUIPO\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/wtkmLfOOF1M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El festival present\u00f3 una programaci\u00f3n adaptada a la nueva situaci\u00f3n, manteniendo sus secciones y actividades habituales en una edici\u00f3n que ha permitido llevar La GRAN pantalla a todo el estado y, de este modo, ampliar su p\u00fablico y diversificarlo. \u201cEl hecho de exhibir el festival en Filmin ha permitido que \u00e9ste haya llegado a muchos lugares, tanto de Catalu\u00f1a como del resto del estado\u201d, ha afirmado Alfredo Cohen, director del festival. Seg\u00fan Cohen, ha sido una edici\u00f3n que, a pesar de sus dificultades, ha obtenido un muy buen resultado. \u201cEstamos muy contentos con esta segunda edici\u00f3n. No ha sido f\u00e1cil, pero me gusta pensar que hemos hecho un proyecto \u00fatil y que las personas mayores, frente a la pantalla, se han podido sentir mejor, m\u00e1s orgullosas de su experiencia, m\u00e1s poderosas, m\u00e1s seguras de s\u00ed mismas&#8230; y menos solas\u201d, explica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo que respecta a las actividades paralelas que ha presentado este a\u00f1o La GRAN pantalla, los <span style=\"text-decoration: underline;\"><a href=\"https:\/\/lagranpantallafestival.com\/es\/espanol\/grandes-debates\/\">dos Grandes debates<\/a><\/span> y los <span style=\"text-decoration: underline;\"><a href=\"https:\/\/lagranpantallafestival.com\/es\/espanol\/parlagran\/\">tres Cinef\u00f3rums<\/a><\/span>, tambi\u00e9n han tenido una muy buena acogida. \u201cLas diferentes actividades participativas que hemos llevado a cabo en el marco del festival, que recogen las experiencias que <a href=\"https:\/\/elparlante.es\/\"><span style=\"text-decoration: underline;\">elParlante<\/span><\/a> desarroll\u00f3 durante el confinamiento, nos han permitido confirmar que las nuevas tecnolog\u00edas pueden generar tambi\u00e9n necesarios espacios de encuentro para que las personas expresen y dialoguen sobre temas que les preocupan\u201d, concluye Cohen.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La GRAN pantalla es un festival que se piensa a largo plazo y pretende volver lo m\u00e1s pronto posible a los lugares de encuentro f\u00edsico, pero la buena acogida del formato online corrobora que se seguir\u00e1 utilizando como segunda ventana del festival.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta segunda edici\u00f3n ha sido un gran desaf\u00edo, ya que hemos tenido que reaccionar con muy poco tiempo para reformular y adaptar nuestro festival. Con todo, ha sido un gran aprendizaje\u201d, afirma Katherina Harder, directora art\u00edstica de La GRAN pantalla. \u201cAhora que ya hemos terminado, tenemos que reflexionar sobre c\u00f3mo incorporar algunos de los valiosos elementos que han surgido a ra\u00edz de este nuevo contexto\u201d, concluye.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AGRADECIMIENTOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La GRAN pantalla, una idea original de <a href=\"https:\/\/elparlante.es\/\">elParlante<\/a>, quiere agradecer el apoyo y la colaboraci\u00f3n del <span style=\"text-decoration: underline;\"><a href=\"https:\/\/ajuntament.barcelona.cat\/es\/\">Ajuntament de Barcelona<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.filmin.es\/\">Filmin<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.acra.cat\/ca\/\">ACRA<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/amigosdelosmayores.org\/es\">Amigos de los Mayores<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/festhome.com\/\">Festhome<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.cinemesgirona.cat\/\">Cinemes Girona<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"http:\/\/fundacioenllac.cat\/es\/inicio\/\">Fundaci\u00f3 Enlla\u00e7<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"http:\/\/observatoriomayoresymedios.com\/\">Mayores y Medios de Comunicaci\u00f3n del Observatorio Permanente UPUA<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"http:\/\/inclus.cat\/es\/\">Festival Incl\u00fas<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/elcomejen.com\/\">El Comej\u00e9n<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.transit.es\/?lang=es\">Tr\u00e0nsit Projectes<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.fundacioroure.org\/es\/inicio\/\">Fundaci\u00f3 Roure<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/incom.uab.cat\/?lang=es\">Incom UAB<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/updea.es\/\">Fundaci\u00f3n Updea<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.fundaciovellaterra.org\/\">Fundaci\u00f3 Vellaterra<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"http:\/\/caladona.org\/\">Caladona<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/cimamujerescineastas.es\/\">CIMA<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/donesvisuals.cat\/\">Dones Visuals<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/beteve.cat\/\">Betev\u00e9<\/a><\/span>, <a href=\"https:\/\/www.qmayor.com\/\"><span style=\"text-decoration: underline;\">Qmayor<\/span> <\/a>y <span style=\"text-decoration: underline;\"><a href=\"https:\/\/elcinefil.cat\/\">El Cin\u00e8fil<\/a><\/span>. Tambi\u00e9n a todas aquellas personas que han participado en esta edici\u00f3n y que han apoyado el proyecto, a los tres miembros del jurado Marta Selva Masoliver, Javier Mu\u00f1iz Briongos y Marta Figueras, y un agradecimiento especial a Montse Majench, por su ayuda siempre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a todas las personas que hab\u00e9is colaborado, participado y apoyado esta segunda edici\u00f3n de La GRAN pantalla.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[71],"tags":[78,73,76,81],"class_list":["post-2722","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar","tag-barcelona","tag-elparlante","tag-festival-de-cine-la-gran-pantalla","tag-la-gran-pantalla-festival"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1GRACIAS, GRACIAS Y GRACIAS! &#183;<\/title>\n<meta name=\"description\" content=\"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1GRACIAS, GRACIAS Y GRACIAS! &#183;\" \/>\n<meta property=\"og:description\" content=\"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/\" \/>\n<meta property=\"og:site_name\" content=\"Festival Internacional de Cinema de les Persones Grans de Barcelona: La Gran Pantalla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lagranpantallabcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-20T13:58:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-20T14:28:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/05\/Sala-Gran-Pantalla-2019-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@granpantallabcn\" \/>\n<meta name=\"twitter:site\" content=\"@granpantallabcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/\"},\"author\":{\"name\":\"administrador\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#\\\/schema\\\/person\\\/615aebb29d680ec00e7f864e37e18d94\"},\"headline\":\"\u00a1GRACIAS, GRACIAS Y GRACIAS!\",\"datePublished\":\"2020-07-20T13:58:46+00:00\",\"dateModified\":\"2020-07-20T14:28:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/\"},\"wordCount\":605,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#organization\"},\"keywords\":[\"barcelona\",\"elparlante\",\"Festival de cine La Gran Pantalla\",\"la gran pantalla festival\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/\",\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/\",\"name\":\"\u00a1GRACIAS, GRACIAS Y GRACIAS! &#183;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#website\"},\"datePublished\":\"2020-07-20T13:58:46+00:00\",\"dateModified\":\"2020-07-20T14:28:12+00:00\",\"description\":\"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/gracias-gracias-y-gracias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1GRACIAS, GRACIAS Y GRACIAS!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/\",\"name\":\"Festival Internacional de Cinema de les Persones Grans de Barcelona: La Gran Pantalla\",\"description\":\"El Festival Internacional de Cine de las personas mayores La gran pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#organization\",\"name\":\"[wpseo_titles]company_nombre\",\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/lagranpantallafestival.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo_web_LaGranPantalla.png?fit=901%2C301&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/lagranpantallafestival.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Logo_web_LaGranPantalla.png?fit=901%2C301&ssl=1\",\"width\":901,\"height\":301,\"caption\":\"[wpseo_titles]company_nombre\"},\"image\":{\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lagranpantallabcn\\\/\",\"https:\\\/\\\/x.com\\\/granpantallabcn\",\"https:\\\/\\\/www.instagram.com\\\/lagranpantallabcn\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/colectivoelparlante\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/#\\\/schema\\\/person\\\/615aebb29d680ec00e7f864e37e18d94\",\"name\":\"administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b19ea97f9a93831a040dbfabbb274da739a63945af08dffef124a0605391f4c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b19ea97f9a93831a040dbfabbb274da739a63945af08dffef124a0605391f4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b19ea97f9a93831a040dbfabbb274da739a63945af08dffef124a0605391f4c?s=96&d=mm&r=g\",\"caption\":\"administrador\"},\"url\":\"https:\\\/\\\/lagranpantallafestival.com\\\/es\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1GRACIAS, GRACIAS Y GRACIAS! &#183;","description":"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1GRACIAS, GRACIAS Y GRACIAS! &#183;","og_description":"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.","og_url":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/","og_site_name":"Festival Internacional de Cinema de les Persones Grans de Barcelona: La Gran Pantalla","article_publisher":"https:\/\/www.facebook.com\/lagranpantallabcn\/","article_published_time":"2020-07-20T13:58:46+00:00","article_modified_time":"2020-07-20T14:28:12+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/05\/Sala-Gran-Pantalla-2019-1024x683.jpg","type":"image\/jpeg"}],"author":"administrador","twitter_card":"summary_large_image","twitter_creator":"@granpantallabcn","twitter_site":"@granpantallabcn","twitter_misc":{"Escrito por":"administrador","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/#article","isPartOf":{"@id":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/"},"author":{"name":"administrador","@id":"https:\/\/lagranpantallafestival.com\/es\/#\/schema\/person\/615aebb29d680ec00e7f864e37e18d94"},"headline":"\u00a1GRACIAS, GRACIAS Y GRACIAS!","datePublished":"2020-07-20T13:58:46+00:00","dateModified":"2020-07-20T14:28:12+00:00","mainEntityOfPage":{"@id":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/"},"wordCount":605,"commentCount":0,"publisher":{"@id":"https:\/\/lagranpantallafestival.com\/es\/#organization"},"keywords":["barcelona","elparlante","Festival de cine La Gran Pantalla","la gran pantalla festival"],"articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/","url":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/","name":"\u00a1GRACIAS, GRACIAS Y GRACIAS! &#183;","isPartOf":{"@id":"https:\/\/lagranpantallafestival.com\/es\/#website"},"datePublished":"2020-07-20T13:58:46+00:00","dateModified":"2020-07-20T14:28:12+00:00","description":"El Festival Internacional de Cine de las personas mayores La Gran Pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.","breadcrumb":{"@id":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lagranpantallafestival.com\/es\/gracias-gracias-y-gracias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagranpantallafestival.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1GRACIAS, GRACIAS Y GRACIAS!"}]},{"@type":"WebSite","@id":"https:\/\/lagranpantallafestival.com\/es\/#website","url":"https:\/\/lagranpantallafestival.com\/es\/","name":"Festival Internacional de Cinema de les Persones Grans de Barcelona: La Gran Pantalla","description":"El Festival Internacional de Cine de las personas mayores La gran pantalla! es el primer espacio en Barcelona dedicado al encuentro cinematogr\u00e1fico intergeneracional. Proyectamos pel\u00edculas y cortometrajes que aborden nuevas miradas sobre el hecho de ser mayor. Nuestro objetivo es desmontar los estereotipos que existen en la sociedad y promover el envejecimiento activo, a trav\u00e9s de la reflexi\u00f3n y el debate que inspira el s\u00e9ptimo arte.","publisher":{"@id":"https:\/\/lagranpantallafestival.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagranpantallafestival.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lagranpantallafestival.com\/es\/#organization","name":"[wpseo_titles]company_nombre","url":"https:\/\/lagranpantallafestival.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lagranpantallafestival.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/05\/Logo_web_LaGranPantalla.png?fit=901%2C301&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lagranpantallafestival.com\/wp-content\/uploads\/2020\/05\/Logo_web_LaGranPantalla.png?fit=901%2C301&ssl=1","width":901,"height":301,"caption":"[wpseo_titles]company_nombre"},"image":{"@id":"https:\/\/lagranpantallafestival.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lagranpantallabcn\/","https:\/\/x.com\/granpantallabcn","https:\/\/www.instagram.com\/lagranpantallabcn\/","https:\/\/www.youtube.com\/user\/colectivoelparlante"]},{"@type":"Person","@id":"https:\/\/lagranpantallafestival.com\/es\/#\/schema\/person\/615aebb29d680ec00e7f864e37e18d94","name":"administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b19ea97f9a93831a040dbfabbb274da739a63945af08dffef124a0605391f4c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b19ea97f9a93831a040dbfabbb274da739a63945af08dffef124a0605391f4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b19ea97f9a93831a040dbfabbb274da739a63945af08dffef124a0605391f4c?s=96&d=mm&r=g","caption":"administrador"},"url":"https:\/\/lagranpantallafestival.com\/es\/author\/administrador\/"}]}},"_links":{"self":[{"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/posts\/2722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/comments?post=2722"}],"version-history":[{"count":5,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/posts\/2722\/revisions"}],"predecessor-version":[{"id":2736,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/posts\/2722\/revisions\/2736"}],"wp:attachment":[{"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/media?parent=2722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/categories?post=2722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagranpantallafestival.com\/es\/wp-json\/wp\/v2\/tags?post=2722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}